{"id":27731,"date":"2025-09-25T15:24:57","date_gmt":"2025-09-25T13:24:57","guid":{"rendered":"https:\/\/www.elkho-group.com\/?p=27731"},"modified":"2025-09-25T15:24:57","modified_gmt":"2025-09-25T13:24:57","slug":"lombard-odier-nuevas-oficinas-en-ginebra","status":"publish","type":"post","link":"https:\/\/www.elkho-group.com\/es\/lombard-odier-nuevas-oficinas-en-ginebra\/","title":{"rendered":"Lombard Odier: Nuevas oficinas en Ginebra"},"content":{"rendered":"<p>Lombard Odier es uno de los bancos privados m\u00e1s prestigiosos y antiguos de Ginebra. Fundada en 1796, es reconocida por sus valores de excelencia y servicios personalizados. El banco atrae a una clientela internacional en busca de servicios hechos a medida. Con el paso del tiempo, su evoluci\u00f3n le ha permitido innovar mientras preserva su experiencia en la gesti\u00f3n patrimonial.<\/p>\n<p>Hoy marca un nuevo cap\u00edtulo importante para Lombard Odier, que se muda a nuevas oficinas m\u00e1s modernas para el inicio del a\u00f1o, adaptadas a los nuevos desaf\u00edos a los que tendr\u00e1 que hacer frente.<\/p>\n<p>Pero no se trata solo de un cambio de ubicaci\u00f3n. M\u00e1s all\u00e1 de una reorganizaci\u00f3n log\u00edstica, es una voluntad de adaptarse e innovar en un sector que evoluciona constantemente: la banca privada. Este traslado es un paso crucial para la instituci\u00f3n y tambi\u00e9n env\u00eda un mensaje contundente para el futuro de la banca privada en la ciudad.<\/p>\n<p>Las nuevas instalaciones, situadas en el coraz\u00f3n del distrito financiero, han sido dise\u00f1adas para fomentar la colaboraci\u00f3n, pero tambi\u00e9n para preservar la privacidad, algo muy importante en la gesti\u00f3n patrimonial. Dicho de otro modo, es un lugar donde los intercambios son m\u00e1s fluidos sin sacrificar la discreci\u00f3n.<\/p>\n<h4><strong data-start=\"1275\" data-end=\"1317\">El entorno de trabajo, un factor clave<\/strong><\/h4>\n<p>En una profesi\u00f3n donde los clientes buscan respuestas r\u00e1pidas, personalizadas y seguras, el entorno juega un papel clave. Esto es lo que ofrece Lombard Odier: unas instalaciones donde los equipos podr\u00e1n colaborar, respetando siempre la necesidad de confidencialidad.<\/p>\n<h4><strong data-start=\"1589\" data-end=\"1619\">Ginebra, un nuevo edificio<\/strong><\/h4>\n<p>El edificio fue dise\u00f1ado por los arquitectos suizos Jacques Herzog y Pierre de Meuron. Han realizado 600 proyectos en 40 pa\u00edses, en los \u00e1mbitos social, cultural y empresarial. Este nuevo sitio permitir\u00e1 reunir a m\u00e1s de 2.000 empleados que anteriormente estaban distribuidos en varias oficinas.<\/p>\n<p>Adem\u00e1s, poniendo en primer plano la sostenibilidad, el banco ha integrado las \u00faltimas tecnolog\u00edas verdes para reducir el impacto ambiental, con el objetivo de obtener certificaciones de construcci\u00f3n sostenible.<\/p>\n<h4><strong data-start=\"2131\" data-end=\"2156\">Invertir en el futuro<\/strong><\/h4>\n<p>Al final, este traslado es una inversi\u00f3n en el futuro. Su objetivo es proporcionar a los empleados las mejores condiciones para seguir destac\u00e1ndose en su campo. M\u00e1s que un simple espacio f\u00edsico, estas oficinas aceleran la innovaci\u00f3n, mientras mantienen los principios fundamentales que han hecho famosa a la instituci\u00f3n: discreci\u00f3n, servicio personalizado y experiencia.<\/p>\n<p>Con estos nuevos espacios, <a href=\"https:\/\/www.lombardodier.com\/fr\/home.html\">Lombard Odier<\/a> busca evolucionar sin perder su identidad. Es un mensaje positivo para la ciudad de Ginebra, ya que refleja su papel como centro financiero global capaz de unir tradici\u00f3n y modernidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lombard Odier es uno de los bancos privados m\u00e1s prestigiosos y antiguos de Ginebra. Fundada en 1796, es reconocida por sus valores de excelencia y servicios personalizados. El banco atrae a una clientela internacional en busca de servicios hechos a medida. Con el paso del tiempo, su evoluci\u00f3n le ha permitido innovar mientras preserva su&hellip;<\/p>\n","protected":false},"author":50,"featured_media":27725,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1615,2479],"tags":[2197,2161,3047,3045,3048,3046,2234],"class_list":["post-27731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-banco","tag-banco","tag-bancos-y-finanzas","tag-edificio","tag-ginebra","tag-lombard-odier","tag-oficinas","tag-trabajo","category-1615","category-2479","description-off"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.elkho-group.com\/es\/wp-json\/wp\/v2\/posts\/27731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elkho-group.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elkho-group.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elkho-group.com\/es\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elkho-group.com\/es\/wp-json\/wp\/v2\/comments?post=27731"}],"version-history":[{"count":1,"href":"https:\/\/www.elkho-group.com\/es\/wp-json\/wp\/v2\/posts\/27731\/revisions"}],"predecessor-version":[{"id":27732,"href":"https:\/\/www.elkho-group.com\/es\/wp-json\/wp\/v2\/posts\/27731\/revisions\/27732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elkho-group.com\/es\/wp-json\/wp\/v2\/media\/27725"}],"wp:attachment":[{"href":"https:\/\/www.elkho-group.com\/es\/wp-json\/wp\/v2\/media?parent=27731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elkho-group.com\/es\/wp-json\/wp\/v2\/categories?post=27731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elkho-group.com\/es\/wp-json\/wp\/v2\/tags?post=27731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}